{"id":22989789,"date":"2023-11-27T19:59:38","date_gmt":"2023-11-27T18:59:38","guid":{"rendered":"http:\/\/wearepropos.es\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\/"},"modified":"2023-12-01T11:46:11","modified_gmt":"2023-12-01T10:46:11","slug":"propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme","status":"publish","type":"post","link":"https:\/\/wearepropos.es\/fr\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\/","title":{"rendered":"Prop\u00f3s participe au 12e Forum des Nations unies sur les entreprises et les droits de l&rsquo;homme"},"content":{"rendered":"<p>Le cabinet espagnol Prop\u00f3s, sp\u00e9cialis\u00e9 dans la strat\u00e9gie de marque, le d\u00e9veloppement durable et l&rsquo;impact social, a particip\u00e9 au <a href=\"https:\/\/www.ohchr.org\/es\/events\/sessions\/2023\/12th-united-nations-forum-business-and-human-rights\">12e Forum des Nations unies sur les entreprises et les<\/a> droits de <a href=\"https:\/\/www.ohchr.org\/es\/events\/sessions\/2023\/12th-united-nations-forum-business-and-human-rights\">l&rsquo;homme<\/a>.<\/p>\n<p>Cet \u00e9v\u00e9nement mondial, qui s&rsquo;est tenu du 27 au 29 novembre, a rassembl\u00e9 plus de 2 000 participants au <a href=\"https:\/\/www.ungeneva.org\/es\/about\/palais-des-nations\">Palais<\/a> des Nations, le si\u00e8ge des Nations unies \u00e0 Gen\u00e8ve, afin d&rsquo;aborder les d\u00e9fis des droits de l&rsquo;homme dans l&rsquo;\u00e9conomie priv\u00e9e.<\/p>\n<p>L&rsquo;<a href=\"https:\/\/www.ohchr.org\/sites\/default\/files\/documents\/hrbodies\/hrcouncil\/forums\/business-forums\/sessions\/session12\/Forum-Business-session12-CN-2023-SP.pdf\">\u00e9dition 2023<\/a> a analys\u00e9 les efforts d\u00e9ploy\u00e9s par les \u00c9tats membres pour int\u00e9grer les progr\u00e8s en mati\u00e8re de droits de l&rsquo;homme dans l&rsquo;\u00e9conomie par le biais de la r\u00e9glementation et des politiques publiques, et a identifi\u00e9 les pratiques des entreprises dans le domaine des droits de l&rsquo;homme. Les participants ont \u00e9galement r\u00e9fl\u00e9chi aux questions environnementales et sociales, telles que l&rsquo;\u00e9galit\u00e9 des sexes et l&rsquo;\u00e9quilibre entre vie professionnelle et vie priv\u00e9e, ainsi qu&rsquo;\u00e0 la bonne gouvernance et aux politiques de conformit\u00e9 dans les organisations priv\u00e9es.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-25544235\" src=\"http:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/onu03-jpg.webp\" alt=\"\" width=\"2230\" height=\"1525\" srcset=\"https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/onu03-jpg.webp 2230w, https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/onu03-300x205.webp 300w, https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/onu03-1024x700.webp 1024w, https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/onu03-768x525.webp 768w, https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/onu03-1536x1050.webp 1536w, https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/onu03-2048x1401.webp 2048w, https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/onu03-1080x739.webp 1080w, https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/onu03-1280x875.webp 1280w, https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/onu03-980x670.webp 980w, https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/onu03-480x328.webp 480w\" sizes=\"(max-width: 2230px) 100vw, 2230px\" \/><\/p>\n<p>\u00c0 cette occasion, les sessions ont int\u00e9gr\u00e9 la perspective des petites et moyennes entreprises, qui constituent l&rsquo;\u00e9pine dorsale de l&rsquo;\u00e9conomie priv\u00e9e dans des pays comme l&rsquo;Espagne, o\u00f9 elles repr\u00e9sentent plus de 90 % du tissu d&rsquo;entreprises.<\/p>\n<p>Le douzi\u00e8me forum sur les entreprises et les droits de l&rsquo;homme faisait partie du sixi\u00e8me <a href=\"http:\/\/wearepropos.es\/contenidos\/misiones\">programme de travail international<\/a> de Prop\u00f3s, qui a \u00e9t\u00e9 compl\u00e9t\u00e9 par des r\u00e9unions avec des clients et des parties prenantes de la soci\u00e9t\u00e9 de conseil en Suisse.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-25544256\" src=\"http:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/ONU-Empresas-04-jpg.webp\" alt=\"\" width=\"2230\" height=\"1525\" srcset=\"https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/ONU-Empresas-04-jpg.webp 2230w, https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/ONU-Empresas-04-300x205.webp 300w, https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/ONU-Empresas-04-1024x700.webp 1024w, https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/ONU-Empresas-04-768x525.webp 768w, https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/ONU-Empresas-04-1536x1050.webp 1536w, https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/ONU-Empresas-04-2048x1401.webp 2048w, https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/ONU-Empresas-04-1080x739.webp 1080w, https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/ONU-Empresas-04-1280x875.webp 1280w, https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/ONU-Empresas-04-980x670.webp 980w, https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/ONU-Empresas-04-480x328.webp 480w\" sizes=\"(max-width: 2230px) 100vw, 2230px\" \/><\/p>\n<p>Les programmes de travail internationaux sont un instrument pour les relations et les comp\u00e9tences mondiales de l&rsquo;entreprise.<\/p>\n<p>Dans le domaine des relations institutionnelles, ils contribuent \u00e0 maintenir l&rsquo;entreprise connect\u00e9e \u00e0 la r\u00e9alit\u00e9 internationale et proche des organisations internationales, en tant que parties prenantes de la soci\u00e9t\u00e9 de conseil. Dans le contexte de la concurrence mondiale, ils favorisent l&rsquo;enrichissement et la compr\u00e9hension de la diversit\u00e9 culturelle et de son impact sur la r\u00e9alit\u00e9 sociale, environnementale et \u00e9conomique, une question strat\u00e9gique pour la localisation des droits de l&rsquo;homme et de la durabilit\u00e9 sur diff\u00e9rents march\u00e9s.<\/p>\n<h2 style=\"padding-bottom: 10px !important;\">T\u00e9l\u00e9chargements d&rsquo;int\u00e9r\u00eat<\/h2>\n<p><a style=\"color: #5569af !important;\" href=\"http:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/2023-11-06-Foro-Empresas-ONU.pdf\">Communiqu\u00e9 de presse<\/a><br \/>\n<a style=\"color: #5569af !important;\" href=\"https:\/\/www.ohchr.org\/sites\/default\/files\/documents\/hrbodies\/hrcouncil\/forums\/business-forums\/sessions\/session12\/Forum-Business-session12-AGENDA2023_SP.pdf\">Programme du Forum<\/a><br \/>\n<a style=\"color: #5569af !important;\" href=\"https:\/\/www.ohchr.org\/sites\/default\/files\/documents\/hrbodies\/hrcouncil\/forums\/business-forums\/sessions\/session12\/Forum-Business-session12-CN-2023-SP.pdf\">Note conceptuelle du forum<\/a><\/p>\n<h2 style=\"padding-top: 20px; line-height: 110%;\">\u00c0 propos du Forum des Nations unies sur les entreprises et les droits de l&rsquo;homme<\/h2>\n<p>Le Forum des entreprises et des droits de l&rsquo;homme est le plus grand rassemblement mondial sur les entreprises et les droits de l&rsquo;homme. Elle r\u00e9unit chaque ann\u00e9e \u00e0 Gen\u00e8ve plus de 2 000 participants : repr\u00e9sentants de gouvernements, d&rsquo;entreprises, d&rsquo;agences des Nations unies, d&rsquo;institutions nationales de d\u00e9fense des droits de l&rsquo;homme et des m\u00e9dias.<\/p>\n<p>Il a \u00e9t\u00e9 cr\u00e9\u00e9 en 2011 par le Conseil des droits de l&rsquo;homme des Nations unies. Son objectif est d&rsquo;analyser, de discuter et de r\u00e9soudre les questions de protection, de respect et de recours en mati\u00e8re de droits de l&rsquo;homme dans le domaine des affaires et de l&rsquo;\u00e9conomie priv\u00e9e.<\/p>\n<h2 style=\"padding-top: 20px;\">A propos de notre entreprise<\/h2>\n<p>Prop\u00f3s est un cabinet de conseil espagnol sp\u00e9cialis\u00e9 dans l&rsquo;objectif, l&rsquo;image de marque, la durabilit\u00e9 et l&rsquo;impact social. Elle accompagne les organisations publiques et priv\u00e9es dans la transformation de leurs marques, de leurs mod\u00e8les \u00e9conomiques et de leurs investissements.<\/p>\n<p>Sous la devise<em>\u00ab\u00a0Business for Good<\/em>\u00ab\u00a0, le cabinet de conseil travaille avec des entreprises, des administrations et des fonds d&rsquo;investissement sur des projets d&rsquo;image de marque, des strat\u00e9gies et des plans de durabilit\u00e9 et d&rsquo;ESG, et sur l&rsquo;am\u00e9lioration de l&rsquo;impact social des entreprises et des investissements.<\/p>\n<p>Fond\u00e9 en 2019 \u00e0 La Rioja, le cabinet de conseil dispose de bureaux \u00e0 Madrid, en Espagne, et \u00e0 Gen\u00e8ve, en Suisse. Au cours de sa courte p\u00e9riode d&rsquo;activit\u00e9, Prop\u00f3s a obtenu une reconnaissance internationale pour ses performances et l&rsquo;impact de son travail. En 2020 et 2021, elle a remport\u00e9 deux prix internationaux Clap pour la communication et la conception de la marque.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le suivi de cette r\u00e9union mondiale et de ses \u00e9v\u00e9nements parall\u00e8les constitue le sixi\u00e8me programme de travail international du cabinet de conseil.<\/p>\n","protected":false},"author":4,"featured_media":25544228,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[526,565,521,524,599,519],"tags":[1120,1121,1124,1122,1123,619],"dipi_cpt_category":[],"class_list":["post-22989789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-accueil","category-communiques-de-presse","category-droits-de-lhomme-et-entreprises","category-entreprises","category-missions","category-propositions","tag-forum-sur-les-entreprises-et-les-droits-de-lhomme","tag-haut-commissaire-des-nations-unies-aux-droits-de-lhomme","tag-mission-internationale","tag-palais-des-nations","tag-principes-des-droits-de-lhomme-pour-les-entreprises","tag-propositions"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prop\u00f3s participe au 12e Forum des Nations unies sur les entreprises et les droits de l&#039;homme &#8211; Prop\u00f3s | Sostenibilidad, ESG, Branding y Comunicaci\u00f3n en Madrid, Barcelona y Ginebra<\/title>\n<meta name=\"description\" content=\"Le suivi de cet \u00e9v\u00e9nement mondial et de ses manifestations parall\u00e8les constitue le sixi\u00e8me programme de travail international du cabinet de conseil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wearepropos.es\/fr\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prop\u00f3s participe au 12e Forum des Nations unies sur les entreprises et les droits de l&#039;homme &#8211; Prop\u00f3s | Sostenibilidad, ESG, Branding y Comunicaci\u00f3n en Madrid, Barcelona y Ginebra\" \/>\n<meta property=\"og:description\" content=\"Le suivi de cet \u00e9v\u00e9nement mondial et de ses manifestations parall\u00e8les constitue le sixi\u00e8me programme de travail international du cabinet de conseil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wearepropos.es\/fr\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\/\" \/>\n<meta property=\"og:site_name\" content=\"Prop\u00f3s | Sostenibilidad, ESG, Branding y Comunicaci\u00f3n en Madrid, Barcelona y Ginebra\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-27T18:59:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-01T10:46:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/onu04-jpg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2230\" \/>\n\t<meta property=\"og:image:height\" content=\"1525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Prop\u00f3s ESG, sostenibilidad e impacto social\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prop\u00f3s ESG, sostenibilidad e impacto social\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\\\/\"},\"author\":{\"name\":\"Prop\u00f3s ESG, sostenibilidad e impacto social\",\"@id\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/#\\\/schema\\\/person\\\/445d67b6a1dcbdf0fb5332d58ccbeb21\"},\"headline\":\"Prop\u00f3s participe au 12e Forum des Nations unies sur les entreprises et les droits de l&rsquo;homme\",\"datePublished\":\"2023-11-27T18:59:38+00:00\",\"dateModified\":\"2023-12-01T10:46:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\\\/\"},\"wordCount\":707,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wearepropos.es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/onu04-jpg.webp\",\"keywords\":[\"Forum sur les entreprises et les droits de l'homme\",\"Haut Commissaire des Nations Unies aux droits de l'homme\",\"mission internationale\",\"Palais des Nations\",\"Principes des droits de l'homme pour les entreprises\",\"Propositions\"],\"articleSection\":[\"Blog, Accueil\",\"Communiqu\u00e9s de presse\",\"Droits de l'homme et entreprises\",\"Entreprises\",\"Missions\",\"Propositions\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\\\/\",\"url\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\\\/\",\"name\":\"Prop\u00f3s participe au 12e Forum des Nations unies sur les entreprises et les droits de l'homme &#8211; Prop\u00f3s | Sostenibilidad, ESG, Branding y Comunicaci\u00f3n en Madrid, Barcelona y Ginebra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wearepropos.es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/onu04-jpg.webp\",\"datePublished\":\"2023-11-27T18:59:38+00:00\",\"dateModified\":\"2023-12-01T10:46:11+00:00\",\"description\":\"Le suivi de cet \u00e9v\u00e9nement mondial et de ses manifestations parall\u00e8les constitue le sixi\u00e8me programme de travail international du cabinet de conseil.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wearepropos.es\\\/fr\\\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wearepropos.es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/onu04-jpg.webp\",\"contentUrl\":\"https:\\\/\\\/wearepropos.es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/onu04-jpg.webp\",\"width\":2230,\"height\":1525,\"caption\":\"Mario Mart\u00ednez, en el 12.\u00ba Foro de Empresas y Derechos Humanos de las Naciones Unidas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prop\u00f3s participe au 12e Forum des Nations unies sur les entreprises et les droits de l&#8217;homme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/\",\"name\":\"Prop\u00f3s | Sostenibilidad, ESG, Branding y Comunicaci\u00f3n en Madrid, Barcelona y Ginebra\",\"description\":\"Empresa y agencia consultora en Sostenibilidad, ESG, impacto social, informe no financiero, branding y dise\u00f1o en Madrid, Barcelona y Ginebra\",\"publisher\":{\"@id\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/#organization\",\"name\":\"Prop\u00f3s\",\"url\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/wearepropos.es\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/fondo-generalista.png\",\"contentUrl\":\"http:\\\/\\\/wearepropos.es\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/fondo-generalista.png\",\"width\":1219,\"height\":649,\"caption\":\"Prop\u00f3s\"},\"image\":{\"@id\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wearepropos.es\\\/fr\\\/#\\\/schema\\\/person\\\/445d67b6a1dcbdf0fb5332d58ccbeb21\",\"name\":\"Prop\u00f3s ESG, sostenibilidad e impacto social\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wearepropos.es\\\/wp-content\\\/litespeed\\\/avatar\\\/81ea4cc1840341d3817e1c13f490c69e.jpg?ver=1783525988\",\"url\":\"https:\\\/\\\/wearepropos.es\\\/wp-content\\\/litespeed\\\/avatar\\\/81ea4cc1840341d3817e1c13f490c69e.jpg?ver=1783525988\",\"contentUrl\":\"https:\\\/\\\/wearepropos.es\\\/wp-content\\\/litespeed\\\/avatar\\\/81ea4cc1840341d3817e1c13f490c69e.jpg?ver=1783525988\",\"caption\":\"Prop\u00f3s ESG, sostenibilidad e impacto social\"},\"sameAs\":[\"http:\\\/\\\/wearepropos.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prop\u00f3s participe au 12e Forum des Nations unies sur les entreprises et les droits de l'homme &#8211; Prop\u00f3s | Sostenibilidad, ESG, Branding y Comunicaci\u00f3n en Madrid, Barcelona y Ginebra","description":"Le suivi de cet \u00e9v\u00e9nement mondial et de ses manifestations parall\u00e8les constitue le sixi\u00e8me programme de travail international du cabinet de conseil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wearepropos.es\/fr\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\/","og_locale":"fr_FR","og_type":"article","og_title":"Prop\u00f3s participe au 12e Forum des Nations unies sur les entreprises et les droits de l'homme &#8211; Prop\u00f3s | Sostenibilidad, ESG, Branding y Comunicaci\u00f3n en Madrid, Barcelona y Ginebra","og_description":"Le suivi de cet \u00e9v\u00e9nement mondial et de ses manifestations parall\u00e8les constitue le sixi\u00e8me programme de travail international du cabinet de conseil.","og_url":"https:\/\/wearepropos.es\/fr\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\/","og_site_name":"Prop\u00f3s | Sostenibilidad, ESG, Branding y Comunicaci\u00f3n en Madrid, Barcelona y Ginebra","article_published_time":"2023-11-27T18:59:38+00:00","article_modified_time":"2023-12-01T10:46:11+00:00","og_image":[{"width":2230,"height":1525,"url":"https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/onu04-jpg.webp","type":"image\/jpeg"}],"author":"Prop\u00f3s ESG, sostenibilidad e impacto social","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Prop\u00f3s ESG, sostenibilidad e impacto social","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/wearepropos.es\/fr\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\/#article","isPartOf":{"@id":"https:\/\/wearepropos.es\/fr\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\/"},"author":{"name":"Prop\u00f3s ESG, sostenibilidad e impacto social","@id":"https:\/\/wearepropos.es\/fr\/#\/schema\/person\/445d67b6a1dcbdf0fb5332d58ccbeb21"},"headline":"Prop\u00f3s participe au 12e Forum des Nations unies sur les entreprises et les droits de l&rsquo;homme","datePublished":"2023-11-27T18:59:38+00:00","dateModified":"2023-12-01T10:46:11+00:00","mainEntityOfPage":{"@id":"https:\/\/wearepropos.es\/fr\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\/"},"wordCount":707,"commentCount":0,"publisher":{"@id":"https:\/\/wearepropos.es\/fr\/#organization"},"image":{"@id":"https:\/\/wearepropos.es\/fr\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\/#primaryimage"},"thumbnailUrl":"https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/onu04-jpg.webp","keywords":["Forum sur les entreprises et les droits de l'homme","Haut Commissaire des Nations Unies aux droits de l'homme","mission internationale","Palais des Nations","Principes des droits de l'homme pour les entreprises","Propositions"],"articleSection":["Blog, Accueil","Communiqu\u00e9s de presse","Droits de l'homme et entreprises","Entreprises","Missions","Propositions"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/wearepropos.es\/fr\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\/","url":"https:\/\/wearepropos.es\/fr\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\/","name":"Prop\u00f3s participe au 12e Forum des Nations unies sur les entreprises et les droits de l'homme &#8211; Prop\u00f3s | Sostenibilidad, ESG, Branding y Comunicaci\u00f3n en Madrid, Barcelona y Ginebra","isPartOf":{"@id":"https:\/\/wearepropos.es\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wearepropos.es\/fr\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\/#primaryimage"},"image":{"@id":"https:\/\/wearepropos.es\/fr\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\/#primaryimage"},"thumbnailUrl":"https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/onu04-jpg.webp","datePublished":"2023-11-27T18:59:38+00:00","dateModified":"2023-12-01T10:46:11+00:00","description":"Le suivi de cet \u00e9v\u00e9nement mondial et de ses manifestations parall\u00e8les constitue le sixi\u00e8me programme de travail international du cabinet de conseil.","breadcrumb":{"@id":"https:\/\/wearepropos.es\/fr\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wearepropos.es\/fr\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wearepropos.es\/fr\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\/#primaryimage","url":"https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/onu04-jpg.webp","contentUrl":"https:\/\/wearepropos.es\/wp-content\/uploads\/2023\/11\/onu04-jpg.webp","width":2230,"height":1525,"caption":"Mario Mart\u00ednez, en el 12.\u00ba Foro de Empresas y Derechos Humanos de las Naciones Unidas"},{"@type":"BreadcrumbList","@id":"https:\/\/wearepropos.es\/fr\/propos-participe-au-12e-forum-des-nations-unies-sur-les-entreprises-et-les-droits-de-lhomme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/wearepropos.es\/fr\/"},{"@type":"ListItem","position":2,"name":"Prop\u00f3s participe au 12e Forum des Nations unies sur les entreprises et les droits de l&#8217;homme"}]},{"@type":"WebSite","@id":"https:\/\/wearepropos.es\/fr\/#website","url":"https:\/\/wearepropos.es\/fr\/","name":"Prop\u00f3s | Sostenibilidad, ESG, Branding y Comunicaci\u00f3n en Madrid, Barcelona y Ginebra","description":"Empresa y agencia consultora en Sostenibilidad, ESG, impacto social, informe no financiero, branding y dise\u00f1o en Madrid, Barcelona y Ginebra","publisher":{"@id":"https:\/\/wearepropos.es\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wearepropos.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wearepropos.es\/fr\/#organization","name":"Prop\u00f3s","url":"https:\/\/wearepropos.es\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wearepropos.es\/fr\/#\/schema\/logo\/image\/","url":"http:\/\/wearepropos.es\/wp-content\/uploads\/2023\/04\/fondo-generalista.png","contentUrl":"http:\/\/wearepropos.es\/wp-content\/uploads\/2023\/04\/fondo-generalista.png","width":1219,"height":649,"caption":"Prop\u00f3s"},"image":{"@id":"https:\/\/wearepropos.es\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/wearepropos.es\/fr\/#\/schema\/person\/445d67b6a1dcbdf0fb5332d58ccbeb21","name":"Prop\u00f3s ESG, sostenibilidad e impacto social","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wearepropos.es\/wp-content\/litespeed\/avatar\/81ea4cc1840341d3817e1c13f490c69e.jpg?ver=1783525988","url":"https:\/\/wearepropos.es\/wp-content\/litespeed\/avatar\/81ea4cc1840341d3817e1c13f490c69e.jpg?ver=1783525988","contentUrl":"https:\/\/wearepropos.es\/wp-content\/litespeed\/avatar\/81ea4cc1840341d3817e1c13f490c69e.jpg?ver=1783525988","caption":"Prop\u00f3s ESG, sostenibilidad e impacto social"},"sameAs":["http:\/\/wearepropos.es"]}]}},"_links":{"self":[{"href":"https:\/\/wearepropos.es\/fr\/wp-json\/wp\/v2\/posts\/22989789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wearepropos.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wearepropos.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wearepropos.es\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/wearepropos.es\/fr\/wp-json\/wp\/v2\/comments?post=22989789"}],"version-history":[{"count":3,"href":"https:\/\/wearepropos.es\/fr\/wp-json\/wp\/v2\/posts\/22989789\/revisions"}],"predecessor-version":[{"id":25544259,"href":"https:\/\/wearepropos.es\/fr\/wp-json\/wp\/v2\/posts\/22989789\/revisions\/25544259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wearepropos.es\/fr\/wp-json\/wp\/v2\/media\/25544228"}],"wp:attachment":[{"href":"https:\/\/wearepropos.es\/fr\/wp-json\/wp\/v2\/media?parent=22989789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wearepropos.es\/fr\/wp-json\/wp\/v2\/categories?post=22989789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wearepropos.es\/fr\/wp-json\/wp\/v2\/tags?post=22989789"},{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/wearepropos.es\/fr\/wp-json\/wp\/v2\/dipi_cpt_category?post=22989789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}